{"id":18214,"date":"2025-06-13T15:48:43","date_gmt":"2025-06-13T13:48:43","guid":{"rendered":"https:\/\/www.adelec-inter.com\/?page_id=18214"},"modified":"2025-06-13T15:53:21","modified_gmt":"2025-06-13T13:53:21","slug":"visseuses-pneumatiques-a-coupure-mecanique","status":"publish","type":"page","link":"https:\/\/www.adelec-inter.com\/en\/visseuses-pneumatiques-a-coupure-mecanique\/","title":{"rendered":"Visseuses pneumatiques \u00e0 coupure m\u00e9canique"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18214\" class=\"elementor elementor-18214\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-858a1ef elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra e-flex e-con-boxed e-con e-parent\" data-id=\"858a1ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c86c1cd elementor-widget elementor-widget-heading\" data-id=\"c86c1cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visseuses pneumatiques \u00e0 coupure m\u00e9canique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a79da21 e-flex e-con-boxed e-con e-parent\" data-id=\"a79da21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6dd1358 e-con-full e-flex e-con e-child\" data-id=\"6dd1358\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-409e431 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"409e431\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;_id&quot;:&quot;7d56f18&quot;,&quot;slide_title&quot;:&quot;Slide #4&quot;}],&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 1\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f8d077 e-flex e-con-boxed e-con e-child\" data-id=\"3f8d077\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7772b19 elementor-widget elementor-widget-image\" data-id=\"7772b19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"864\" src=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/s-1024x983.jpg\" class=\"attachment-large size-large wp-image-18103\" alt=\"\" srcset=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/s-1024x983.jpg 1024w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/s-300x288.jpg 300w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/s-768x737.jpg 768w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/s-1536x1474.jpg 1536w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/s.jpg 1588w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ab6db3 e-con-full e-flex e-con e-child\" data-id=\"3ab6db3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a3cf9b elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"2a3cf9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Visseuses pneumatiques \u00e0 coupure m\u00e9canique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3842e25 elementor-widget elementor-widget-text-editor\" data-id=\"3842e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"90\" data-end=\"126\">Les visseuses pneumatiques \u00e0 coupure m\u00e9canique sont des outils de vissage aliment\u00e9s par air comprim\u00e9, dot\u00e9s d\u2019un m\u00e9canisme d\u2019arr\u00eat automatique lorsque le couple pr\u00e9r\u00e9gl\u00e9 est atteint. Cette technologie garantit un <strong data-start=\"343\" data-end=\"375\">serrage constant et s\u00e9curis\u00e9<\/strong>, tout en offrant une grande rapidit\u00e9 d\u2019ex\u00e9cution. Robustes, l\u00e9g\u00e8res et fiables, elles sont id\u00e9ales pour les environnements de production r\u00e9p\u00e9titive, notamment dans l\u2019assemblage industriel, o\u00f9 la pr\u00e9cision du couple est essentielle sans n\u00e9cessiter d\u2019\u00e9lectronique embarqu\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f8c9bf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5f8c9bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f89551 elementor-widget elementor-widget-heading\" data-id=\"5f89551\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CARACTERISTIQUES TECHNIQUES :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8f23e1 elementor-widget elementor-widget-text-editor\" data-id=\"c8f23e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u00a0Embrayages de grande pr\u00e9cision \u00e0 coupure d\u2019air et arr\u00eat moteur instantan\u00e9<\/li><li>Moteur 5 palettes de derni\u00e8re g\u00e9n\u00e9ration au rendement optimis\u00e9<\/li><li>\u00a0Poids, niveaux de pressions sonores et vibratoires r\u00e9duits conformes aux Directives Europ\u00e9ennes<\/li><li>\u00a0Consommation d\u2019air r\u00e9duite pour le respect de l\u2019environnement<\/li><li>\u00a0Poign\u00e9es et grips ergonomiques pour un confort maximum<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7950354 e-grid e-con-full e-con e-child\" data-id=\"7950354\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c775a5 elementor-button-type-outline elementor-widget elementor-widget-rebuilto-button\" data-id=\"0c775a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rebuilto-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-button-wrapper\">\n            <a href=\"\/wp-content\/uploads\/2025\/06\/40912_2.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n                        <span class=\"elementor-button-content-wrapper\">\n                          <span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"rebuilto-icon- rebuilto-icon-arrow-up-right\"><\/i>\t\t\t<\/span>\n            \t\t\t<span class=\"elementor-button-text\" data-name=\"T\u00e9l\u00e9charger la fiche technique\">\n                <span>T\u00e9l\u00e9charger la fiche technique<\/span>\n            <\/span>\n\t\t<\/span>\n                    <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-befac19 elementor-align-center popmake-8313 elementor-mobile-align-left elementor-button-type-outline elementor-widget elementor-widget-rebuilto-button\" data-id=\"befac19\" data-element_type=\"widget\" data-e-type=\"widget\" data-popup-open=\"\" data-produit=\"520\" data-widget_type=\"rebuilto-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-button-wrapper\">\n            <a class=\"elementor-button elementor-size-sm\" role=\"button\">\n                        <span class=\"elementor-button-content-wrapper\">\n                          <span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"rebuilto-icon- rebuilto-icon-arrow-up-right\"><\/i>\t\t\t<\/span>\n            \t\t\t<span class=\"elementor-button-text\" data-name=\"DEMANDER UN DEVIS\">\n                <span>DEMANDER UN DEVIS<\/span>\n            <\/span>\n\t\t<\/span>\n                    <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97f2b27 e-flex e-con-boxed e-con e-parent\" data-id=\"97f2b27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a3053d9 e-con-full e-flex e-con e-child\" data-id=\"a3053d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84ba556 elementor-widget__width-initial animated-fast elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"84ba556\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7bbcbc animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c7bbcbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-scale-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Explorer<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4832f21 elementor-widget elementor-widget-heading\" data-id=\"4832f21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dans la m\u00eame cat\u00e9gorie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17afc4e e-flex e-con-boxed e-con e-parent\" data-id=\"17afc4e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63542a2 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"63542a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;_id&quot;:&quot;02747e8&quot;,&quot;slide_title&quot;:&quot;Slide #4&quot;},{&quot;_id&quot;:&quot;ebbc814&quot;,&quot;slide_title&quot;:&quot;Slide #6&quot;},{&quot;_id&quot;:&quot;d1982a8&quot;,&quot;slide_title&quot;:&quot;Slide #3&quot;},{&quot;_id&quot;:&quot;5beca8c&quot;,&quot;slide_title&quot;:&quot;Slide #4&quot;}],&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;slides_to_show_tablet_extra&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1fe4a2 e-flex e-con-boxed e-con e-child\" data-id=\"d1fe4a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-29affc2 e-con-full e-flex e-con e-child\" data-id=\"29affc2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-374573b elementor-widget elementor-widget-image\" data-id=\"374573b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/visseuse-electrique-asservie-couple-et-angle\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"864\" src=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003714-1024x983.jpg\" class=\"attachment-large size-large wp-image-18106\" alt=\"\" srcset=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003714-1024x983.jpg 1024w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003714-300x288.jpg 300w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003714-768x737.jpg 768w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003714-1536x1474.jpg 1536w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003714.jpg 1588w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1364441 card-title elementor-widget elementor-widget-heading\" data-id=\"1364441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/visseuse-electrique-asservie-couple-et-angle\/\">Visseuse \u00e9lectrique asservie couple et angle<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a91fa31 desc elementor-widget elementor-widget-text-editor\" data-id=\"a91fa31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La visseuse \u00e9lectrique asservie en couple et en angle est un outil de haute pr\u00e9cision con\u00e7u pour les op\u00e9rations de vissage critiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e9c99 elementor-view-stacked elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"74e9c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-buzz-out\" href=\"\/visseuse-electrique-asservie-couple-et-angle\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"rebuilto-icon- rebuilto-icon-arrow-up-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e24e82 e-flex e-con-boxed e-con e-child\" data-id=\"5e24e82\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5495a02 e-con-full e-flex e-con e-child\" data-id=\"5495a02\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e575033 elementor-widget elementor-widget-image\" data-id=\"e575033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/visseuse-a-batterie-asservie-couple-et-angle\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"866\" src=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003691-1024x985.jpg\" class=\"attachment-large size-large wp-image-18104\" alt=\"\" srcset=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003691-1024x985.jpg 1024w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003691-300x289.jpg 300w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003691-768x739.jpg 768w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003691-1536x1478.jpg 1536w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003691.jpg 1588w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41af01e card-title elementor-widget elementor-widget-heading\" data-id=\"41af01e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/visseuse-a-batterie-asservie-couple-et-angle\/\">Visseuse \u00e0 batterie asservie couple et angle<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba1d263 desc elementor-widget elementor-widget-text-editor\" data-id=\"ba1d263\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La visseuse \u00e0 batterie asservie en couple et angle est un outil de vissage sans fil de haute pr\u00e9cision, con\u00e7u pour les environnements de production exigeant mobilit\u00e9, fiabilit\u00e9 et contr\u00f4le.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88b8b8e elementor-view-stacked elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"88b8b8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-buzz-out\" href=\"\/visseuse-a-batterie-asservie-couple-et-angle\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"rebuilto-icon- rebuilto-icon-arrow-up-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef4fef1 e-flex e-con-boxed e-con e-child\" data-id=\"ef4fef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0ee67d6 e-con-full e-flex e-con e-child\" data-id=\"0ee67d6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56717f1 elementor-widget elementor-widget-image\" data-id=\"56717f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/outils-electriques-brushless\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"866\" src=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003715-1024x985.jpg\" class=\"attachment-large size-large wp-image-18102\" alt=\"\" srcset=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003715-1024x985.jpg 1024w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003715-300x289.jpg 300w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003715-768x739.jpg 768w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003715-1536x1478.jpg 1536w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003715.jpg 1588w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d11eea card-title elementor-widget elementor-widget-heading\" data-id=\"0d11eea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/outils-electriques-brushless\/\">Outils \u00e9lectriques brushless<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9429f19 desc elementor-widget elementor-widget-text-editor\" data-id=\"9429f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jshop_prod_description\"><p>Les outils \u00e9lectriques <strong data-start=\"125\" data-end=\"138\">brushless<\/strong> (sans balais) sont des \u00e9quipements motoris\u00e9s utilisant des moteurs \u00e0 courant continu sans balais de charbon.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c3438 elementor-view-stacked elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"59c3438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-buzz-out\" href=\"\/outils-electriques-brushless\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"rebuilto-icon- rebuilto-icon-arrow-up-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01418b6 e-flex e-con-boxed e-con e-child\" data-id=\"01418b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-717e1c4 e-con-full e-flex e-con e-child\" data-id=\"717e1c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e982cb elementor-widget elementor-widget-image\" data-id=\"1e982cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/cles-et-tournevis-dynamometriques-de-production\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"866\" src=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003692-1024x985.jpg\" class=\"attachment-large size-large wp-image-18105\" alt=\"\" srcset=\"https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003692-1024x985.jpg 1024w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003692-300x289.jpg 300w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003692-768x739.jpg 768w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003692-1536x1478.jpg 1536w, https:\/\/www.adelec-inter.com\/wp-content\/uploads\/2025\/06\/Group-1000003692.jpg 1588w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75a1b83 card-title elementor-widget elementor-widget-heading\" data-id=\"75a1b83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/cles-et-tournevis-dynamometriques-de-production\/\">Cl\u00e9s et tournevis dynamom\u00e9triques de production<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d0679e desc elementor-widget elementor-widget-text-editor\" data-id=\"9d0679e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les cl\u00e9s et tournevis dynamom\u00e9triques de production sont des outils de serrage de haute pr\u00e9cision con\u00e7us pour garantir un <strong data-start=\"262\" data-end=\"309\">couple de serrage contr\u00f4l\u00e9 et reproductible<\/strong> dans les environnements industriels.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c411f65 elementor-view-stacked elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"c411f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-buzz-out\" href=\"\/cles-et-tournevis-dynamometriques-de-production\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"rebuilto-icon- rebuilto-icon-arrow-up-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Visseuses pneumatiques \u00e0 coupure m\u00e9canique Visseuses pneumatiques \u00e0 coupure m\u00e9canique Les visseuses pneumatiques \u00e0 coupure m\u00e9canique sont des outils de vissage aliment\u00e9s par air comprim\u00e9, dot\u00e9s d\u2019un m\u00e9canisme d\u2019arr\u00eat automatique lorsque le couple pr\u00e9r\u00e9gl\u00e9 est atteint. Cette technologie garantit un serrage constant et s\u00e9curis\u00e9, tout en offrant une grande rapidit\u00e9 d\u2019ex\u00e9cution. Robustes, l\u00e9g\u00e8res et fiables, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18214","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/pages\/18214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/comments?post=18214"}],"version-history":[{"count":7,"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/pages\/18214\/revisions"}],"predecessor-version":[{"id":18236,"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/pages\/18214\/revisions\/18236"}],"wp:attachment":[{"href":"https:\/\/www.adelec-inter.com\/en\/wp-json\/wp\/v2\/media?parent=18214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}